{"id":18023,"date":"2025-04-29T08:00:33","date_gmt":"2025-04-29T12:00:33","guid":{"rendered":"https:\/\/innovativemedicines.bcdn.ca\/newsroom\/all-news\/"},"modified":"2025-04-29T08:14:53","modified_gmt":"2025-04-29T12:14:53","slug":"mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs","status":"publish","type":"news","link":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/","title":{"rendered":"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs"},"content":{"rendered":"\n<p><strong>Ottawa, ON <\/strong>\u2013 M\u00e9dicaments novateurs Canada (MNC) f\u00e9licite Mark Carney pour son \u00e9lection \u00e0 titre de premier ministre du Canada, le Parti lib\u00e9ral pour sa formation au gouvernement et tous les d\u00e9put\u00e9s \u00e9lus lors des \u00e9lections f\u00e9d\u00e9rales du 28\u202favril.<\/p>\n\n\n\n<p>Repr\u00e9sentant l\u2019industrie pharmaceutique du Canada, MNC s\u2019engage \u00e0 travailler en collaboration avec le nouveau gouvernement pour renforcer l\u2019\u00e9conomie canadienne en am\u00e9liorant l\u2019acc\u00e8s aux m\u00e9dicaments et en d\u00e9veloppant l&rsquo;\u00e9cosyst\u00e8me de l\u2019industrie des sciences de la vie du pays. Les membres de MNC soutiennent plus de 100 000 emplois et injectent jusqu\u2019\u00e0 16&nbsp;milliards de dollars par ann\u00e9e dans l\u2019\u00e9conomie canadienne.<\/p>\n\n\n\n<p>\u00ab&nbsp;Les soins de sant\u00e9 demeurent une priorit\u00e9 absolue pour les Canadiens, et nous sommes encourag\u00e9s par les engagements pris par le Parti lib\u00e9ral sur sa plateforme \u00e9lectorale en vue de soutenir l\u2019innovation et l\u2019entrepreneuriat, de diminuer les formalit\u00e9s administratives, de r\u00e9duire les temps d\u2019attente pour avoir acc\u00e8s \u00e0 des m\u00e9dicaments et \u00e0 des vaccins novateurs qui sauvent des vies et de moderniser notre syst\u00e8me de soins de sant\u00e9 public&nbsp;\u00bb, a d\u00e9clar\u00e9 Bettina Hamelin, pr\u00e9sidente de MNC.<\/p>\n\n\n\n<p>\u00ab&nbsp;Nous sommes impatients de nous associer au nouveau gouvernement pour aider \u00e0 atteindre ces objectifs et veiller \u00e0 ce que les Canadiens re\u00e7oivent les traitements dont ils ont besoin, quand ils en ont besoin&nbsp;\u00bb, a ajout\u00e9 M<sup>me<\/sup>&nbsp;Hamelin.<\/p>\n\n\n\n<p>Au cours des prochaines semaines, MNC renouera avec les principaux d\u00e9cideurs du gouvernement et le personnel du minist\u00e8re pour faire progresser les objectifs communs en mati\u00e8re de soins de sant\u00e9, notamment&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9duire les temps d\u2019attente pour que la population ait acc\u00e8s \u00e0 des m\u00e9dicaments qui sauvent des vies d\u00e8s leur approbation par Sant\u00e9 Canada, en r\u00e9duisant les formalit\u00e9s administratives sans abaisser les normes de s\u00e9curit\u00e9.<\/li>\n\n\n\n<li>Encourager l\u2019investissement dans l\u2019innovation et renforcer l\u2019avantage du Canada dans des industries strat\u00e9giques comme la biofabrication en soutenant les entreprises de l\u2019industrie de la biotechnologie.<\/li>\n\n\n\n<li>Renforcer le leadership du Canada en sciences de la vie et am\u00e9liorer l\u2019acc\u00e8s \u00e0 de nouvelles th\u00e9rapies pour les patients en attirant les meilleurs talents dans les \u00e9tablissements de recherche canadiens.<\/li>\n<\/ul>\n\n\n\n<p>MNC s\u2019engage \u00e0 \u00eatre un partenaire collaboratif dans l\u2019\u00e9laboration de politiques qui accordent la priorit\u00e9 \u00e0 l\u2019acc\u00e8s \u00e0 des traitements novateurs pour les patients, soutiennent les progr\u00e8s scientifiques et renforcent le secteur des sciences de la vie du Canada comme moteur \u00e9conomique concurrentiel \u00e0 l\u2019\u00e9chelle mondiale. En travaillant ensemble, nous ferons en sorte que les Canadiens b\u00e9n\u00e9ficient d\u2019un acc\u00e8s en temps utile aux derni\u00e8res innovations m\u00e9dicales et que le Canada continue d\u2019attirer les investissements, la recherche et les talents dans ce secteur essentiel.<\/p>\n\n\n\n<p><strong>\u00c0 propos de M\u00e9dicaments novateurs Canada<\/strong><\/p>\n\n\n\n<p>M\u00e9dicaments novateurs Canada (MNC) est l\u2019association nationale qui repr\u00e9sente l\u2019industrie pharmaceutique innovatrice canadienne. L\u2019industrie est fi\u00e8re de soutenir plus de 100&nbsp;000&nbsp;emplois de grande valeur, de contribuer \u00e0 l\u2019\u00e9conomie un total de 16&nbsp;milliards de dollars, de parrainer la majorit\u00e9 des essais cliniques au Canada et d\u2019investir pr\u00e8s de 3&nbsp;milliards de dollars dans la recherche et le d\u00e9veloppement chaque ann\u00e9e. MNC plaide en faveur de politiques qui permettent la d\u00e9couverte, le d\u00e9veloppement et la distribution de m\u00e9dicaments et vaccins novateurs pour am\u00e9liorer la vie de tous les Canadiens. L\u2019association et ses membres sont des partenaires orient\u00e9s vers la recherche de solutions pour le syst\u00e8me de sant\u00e9 canadien et ont contribu\u00e9 plus de 30&nbsp;millions de dollars \u00e0 la recherche appliqu\u00e9e sur les syst\u00e8mes de sant\u00e9 par l\u2019interm\u00e9diaire de la Fondation pour la recherche en sant\u00e9 (FRS). Tous ses membres suivent le Code d\u2019\u00e9thique de MNC, ils travaillent donc de mani\u00e8re hautement \u00e9thique avec les gouvernements, les payeurs priv\u00e9s, les professionnels de la sant\u00e9 et les parties prenantes.<\/p>\n\n\n\n<p>Pour de plus amples renseignements :<\/p>\n\n\n\n<p>media@imc-mnc.ca<br \/>613-462-5367<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ottawa, ON \u2013 M\u00e9dicaments novateurs Canada (MNC) f\u00e9licite Mark Carney pour son \u00e9lection \u00e0 titre de premier ministre du Canada, [&hellip;]<\/p>\n","protected":false},"featured_media":18022,"template":"","topic":[238,260],"team-member-id":[],"news-category":[176],"news-tag":[],"class_list":["post-18023","news","type-news","status-publish","has-post-thumbnail","hentry","topic-acces-aux-medicaments","topic-assurance-medicaments","news-category-communique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada\" \/>\n<meta property=\"og:description\" content=\"Ottawa, ON \u2013 M\u00e9dicaments novateurs Canada (MNC) f\u00e9licite Mark Carney pour son \u00e9lection \u00e0 titre de premier ministre du Canada, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Medicines Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T12:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/innovativemedicines.bcdn.ca\/wp-content\/uploads\/2025\/04\/imc-04-2802025-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/\",\"url\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/\",\"name\":\"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imc-04-2802025-scaled.jpg\",\"datePublished\":\"2025-04-29T12:00:33+00:00\",\"dateModified\":\"2025-04-29T12:14:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imc-04-2802025-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imc-04-2802025-scaled.jpg\",\"width\":1980,\"height\":1316},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/actualites\\\/toutes-les-nouvelles\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/\",\"name\":\"Innovative Medicines Canada\",\"description\":\"Transforming Canadians\u2019 lives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/innovativemedicines.bcdn.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada","og_description":"Ottawa, ON \u2013 M\u00e9dicaments novateurs Canada (MNC) f\u00e9licite Mark Carney pour son \u00e9lection \u00e0 titre de premier ministre du Canada, [&hellip;]","og_url":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/","og_site_name":"Innovative Medicines Canada","article_modified_time":"2025-04-29T12:14:53+00:00","og_image":[{"width":1980,"height":1316,"url":"https:\/\/innovativemedicines.bcdn.ca\/wp-content\/uploads\/2025\/04\/imc-04-2802025-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/","url":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/","name":"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs - Innovative Medicines Canada","isPartOf":{"@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/#primaryimage"},"image":{"@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/#primaryimage"},"thumbnailUrl":"https:\/\/innovativemedicines.bcdn.ca\/wp-content\/uploads\/2025\/04\/imc-04-2802025-scaled.jpg","datePublished":"2025-04-29T12:00:33+00:00","dateModified":"2025-04-29T12:14:53+00:00","breadcrumb":{"@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/#primaryimage","url":"https:\/\/innovativemedicines.bcdn.ca\/wp-content\/uploads\/2025\/04\/imc-04-2802025-scaled.jpg","contentUrl":"https:\/\/innovativemedicines.bcdn.ca\/wp-content\/uploads\/2025\/04\/imc-04-2802025-scaled.jpg","width":1980,"height":1316},{"@type":"BreadcrumbList","@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/mnc-felicite-le-nouveau-gouvernement-du-canada-et-se-rejouit-a-lidee-de-faire-progresser-lacces-a-des-medicaments-novateurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/innovativemedicines.bcdn.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/"},{"@type":"ListItem","position":3,"name":"Actualit\u00e9s","item":"https:\/\/innovativemedicines.bcdn.ca\/fr\/actualites\/toutes-les-nouvelles\/"},{"@type":"ListItem","position":4,"name":"MNC f\u00e9licite le nouveau gouvernement du Canada et se r\u00e9jouit \u00e0 l\u2019id\u00e9e de faire progresser l\u2019acc\u00e8s \u00e0 des m\u00e9dicaments novateurs"}]},{"@type":"WebSite","@id":"https:\/\/innovativemedicines.bcdn.ca\/fr\/#website","url":"https:\/\/innovativemedicines.bcdn.ca\/fr\/","name":"Innovative Medicines Canada","description":"Transforming Canadians\u2019 lives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/innovativemedicines.bcdn.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/news\/18023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/media\/18022"}],"wp:attachment":[{"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/media?parent=18023"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/topic?post=18023"},{"taxonomy":"team-member-id","embeddable":true,"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/team-member-id?post=18023"},{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/news-category?post=18023"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/innovativemedicines.bcdn.ca\/fr\/wp-json\/wp\/v2\/news-tag?post=18023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}